{"id":726,"date":"2015-04-02T09:31:00","date_gmt":"2015-04-02T09:31:00","guid":{"rendered":"https:\/\/www.lanz-berlin.de\/?p=726"},"modified":"2022-04-29T18:22:24","modified_gmt":"2022-04-29T18:22:24","slug":"pudel-vs-puma-keine-marke-fuer-parodie","status":"publish","type":"post","link":"https:\/\/www.lanz-berlin.de\/de\/aktuelles-ratgeber\/pudel-vs-puma-keine-marke-fuer-parodie\/","title":{"rendered":"Pudel vs. PUMA: Keine Marke f\u00fcr Parodie"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:70%\">\n<p>BGH, Urteil vom 02.04.2015, AZ: I ZR 59\/13<\/p>\n\n\n\n<p><strong>Der springende Pudel darf nicht als Marke ins Markenregister eingetragen werden<\/strong>. So entschied nun der BGH in einem Urteil.<\/p>\n\n\n\n<p>Der beklagte Designer hat den springenden Pudel entworfen, der in seiner Aufmachung recht stark dem springenden Puma des klagenden Sportartikelherstellers \u00e4hnelt.<\/p>\n\n\n\n<p><strong>Der Beklagte darf dieses T-Shirt bereits seit l\u00e4ngerer Zeit als erlaubte Parodie der Marke verkaufen<\/strong>. Das reine Herstellen und Verkaufen der T-Shirts mit Pudel sahen die Gerichte n\u00e4mlich bisher als Parodie an \u2013 die aufgrund der Kunst- und Meinungsfreiheit des Designers gestattet sein m\u00fcsse.<\/p>\n\n\n\n<p>Aber bei der Markenanmeldung des Logos \u201espringender Pudel\u201c war dann Schluss<strong>: die Kunstfreiheit erlaube dem Designer n\u00e4mlich nicht die Parodie auch als Markenrecht sch\u00fctzen zu lassen<\/strong>, so der BGH.<\/p>\n\n\n\n<p><strong>Fazit<\/strong>: Dem BGH ist zuzustimmen. Zu viel Kommerz l\u00e4sst das Argument des \u201eParodisten\u201c, es sei ja nur Kunst und seine eigenen Meinung unglaubw\u00fcrdig erscheinen.<\/p>\n\n\n\n<p>Autorin: Rechtsanw\u00e4ltin Dr. Brigitte Lanz, LL.M.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>BGH, Urteil vom 02.04.2015, AZ: I ZR 59\/13 Der springende Pudel darf nicht als Marke ins Markenregister eingetragen werden. So entschied nun der BGH in einem Urteil. Der beklagte Designer hat den springenden Pudel entworfen, der in seiner Aufmachung recht stark dem springenden Puma des klagenden Sportartikelherstellers \u00e4hnelt. Der Beklagte darf dieses T-Shirt bereits seit &#8230; <a title=\"Pudel vs. PUMA: Keine Marke f\u00fcr Parodie\" class=\"read-more\" href=\"https:\/\/www.lanz-berlin.de\/de\/aktuelles-ratgeber\/pudel-vs-puma-keine-marke-fuer-parodie\/\" aria-label=\"Mehr zu Pudel vs. PUMA: Keine Marke f\u00fcr Parodie\">Weiterlesen &#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-726","post","type-post","status-publish","format-standard","hentry","category-aktuelles-ratgeber","infinite-scroll-item","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"_links":{"self":[{"href":"https:\/\/www.lanz-berlin.de\/de\/wp-json\/wp\/v2\/posts\/726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lanz-berlin.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lanz-berlin.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lanz-berlin.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lanz-berlin.de\/de\/wp-json\/wp\/v2\/comments?post=726"}],"version-history":[{"count":2,"href":"https:\/\/www.lanz-berlin.de\/de\/wp-json\/wp\/v2\/posts\/726\/revisions"}],"predecessor-version":[{"id":1827,"href":"https:\/\/www.lanz-berlin.de\/de\/wp-json\/wp\/v2\/posts\/726\/revisions\/1827"}],"wp:attachment":[{"href":"https:\/\/www.lanz-berlin.de\/de\/wp-json\/wp\/v2\/media?parent=726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lanz-berlin.de\/de\/wp-json\/wp\/v2\/categories?post=726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lanz-berlin.de\/de\/wp-json\/wp\/v2\/tags?post=726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}